{"id":756,"date":"2024-11-26T12:57:23","date_gmt":"2024-11-26T10:57:23","guid":{"rendered":"https:\/\/mamaspie.gr\/mamas-pie\/"},"modified":"2026-03-06T16:45:43","modified_gmt":"2026-03-06T14:45:43","slug":"mamas-pie","status":"publish","type":"page","link":"https:\/\/mamaspie.gr\/en\/","title":{"rendered":"Mama&#8217;s Pie"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;375&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; full_height=&#8221;yes&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;top_to_bottom&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;5vh&#8221;][image_with_animation image_url=&#8221;757&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;flip-in-vertical&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][nectar_cta btn_style=&#8221;next-section&#8221; btn_type=&#8221;minimal-arrow&#8221; next_section_color=&#8221;#ffffff&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; aria_label_text=&#8221;scroll&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_hidden-lg vc_hidden-md&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;5vh&#8221;][image_with_animation image_url=&#8221;759&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;flip-in-vertical&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][nectar_cta btn_style=&#8221;next-section&#8221; btn_type=&#8221;minimal-arrow&#8221; next_section_color=&#8221;#ffffff&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; aria_label_text=&#8221;scroll&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;2%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;2%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][carousel script=&#8221;flickity&#8221; flickity_formatting=&#8221;default&#8221; desktop_cols_flickity=&#8221;1&#8243; desktop_small_cols_flickity=&#8221;1&#8243; tablet_cols_flickity=&#8221;1&#8243; phone_cols_flickity=&#8221;1&#8243; flickity_controls=&#8221;next_prev_arrows_overlaid&#8221; color=&#8221;accent-color&#8221; flickity_overflow=&#8221;hidden&#8221; flickity_wrap_around=&#8221;wrap&#8221; flickity_spacing=&#8221;default&#8221; flickity_column_vertical_alignment=&#8221;default&#8221; column_padding=&#8221;0&#8243; flickity_element_spacing=&#8221;0&#8243; border_radius=&#8221;none&#8221; autorotate=&#8221;true&#8221; autorotate_type=&#8221;default&#8221; autorotation_speed=&#8221;3000&#8243;][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1772807880994-0&#8243; tab_id=&#8221;1772807880994-3&#8243; title=&#8221;Item&#8221;][image_with_animation image_url=&#8221;570&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1772807881036-7&#8243; tab_id=&#8221;1772807881037-10&#8243; title=&#8221;Item&#8221;][image_with_animation image_url=&#8221;388&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1772807881087-7&#8243; tab_id=&#8221;1772807881088-1&#8243; title=&#8221;Item&#8221;][image_with_animation image_url=&#8221;572&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1772807881184-5&#8243; tab_id=&#8221;1772807881185-2&#8243; title=&#8221;Item&#8221;][image_with_animation image_url=&#8221;390&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1772807881226-3&#8243; tab_id=&#8221;1772807881226-1&#8243; title=&#8221;Item&#8221;][image_with_animation image_url=&#8221;574&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1772807881263-9&#8243; tab_id=&#8221;1772807881263-8&#8243; title=&#8221;Item&#8221;][image_with_animation image_url=&#8221;578&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1772807881307-5&#8243; tab_id=&#8221;1772807881307-6&#8243; title=&#8221;Item&#8221;][image_with_animation image_url=&#8221;576&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1772807881358-10&#8243; tab_id=&#8221;1772807881358-3&#8243; title=&#8221;Item&#8221;][image_with_animation image_url=&#8221;394&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1772807881393-4&#8243; tab_id=&#8221;1772807881394-9&#8243; title=&#8221;Item&#8221;][image_with_animation image_url=&#8221;395&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/item][\/carousel][\/vc_column][vc_column column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h3&#8243; text_color=&#8221;#1c173f&#8221; font_size_min=&#8221;36&#8243; font_size_max=&#8221;45&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; stagger_animation=&#8221;true&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;We stand out&#8221; font_size=&#8221;3vw&#8221; font_line_height=&#8221;1.2&#8243; text_direction=&#8221;default&#8221; font_size_tablet=&#8221;4vw&#8221; font_size_phone=&#8221;6vw&#8221;][\/split_line_heading][image_with_animation image_url=&#8221;40&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]All our products are freshly baked &amp; frozen for your convenience! This means they are ready to enjoy as soon as they defrost. Enjoy them as they are, cool, as a light snack, or heat them for just a few minutes and feel the freshness come alive on your plate![\/vc_column_text][nectar_btn size=&#8221;large&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; solid_text_color_override=&#8221;#eff1f0&#8243; icon_family=&#8221;none&#8221; el_class=&#8221;mamas-button&#8221; text=&#8221;Get to know us&#8221; margin_top=&#8221;20&#8243; margin_bottom=&#8221;20&#8243; url=&#8221;\/en\/about&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;reverse&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;2%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;2%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][carousel script=&#8221;flickity&#8221; flickity_formatting=&#8221;default&#8221; desktop_cols_flickity=&#8221;1&#8243; desktop_small_cols_flickity=&#8221;1&#8243; tablet_cols_flickity=&#8221;1&#8243; phone_cols_flickity=&#8221;1&#8243; flickity_controls=&#8221;next_prev_arrows_overlaid&#8221; color=&#8221;accent-color&#8221; flickity_overflow=&#8221;hidden&#8221; flickity_wrap_around=&#8221;wrap&#8221; flickity_spacing=&#8221;default&#8221; flickity_column_vertical_alignment=&#8221;default&#8221; column_padding=&#8221;0&#8243; flickity_element_spacing=&#8221;0&#8243; border_radius=&#8221;none&#8221; autorotate=&#8221;true&#8221; autorotate_type=&#8221;default&#8221; autorotation_speed=&#8221;3000&#8243;][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1772807881816-8&#8243; tab_id=&#8221;1772807881817-3&#8243; title=&#8221;Item&#8221;][image_with_animation image_url=&#8221;917&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1772807881900-0&#8243; tab_id=&#8221;1772807881901-8&#8243; title=&#8221;Item&#8221;][image_with_animation image_url=&#8221;919&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1772807881965-8&#8243; tab_id=&#8221;1772807881966-7&#8243; title=&#8221;Item&#8221;][image_with_animation image_url=&#8221;921&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1772807881991-4&#8243; tab_id=&#8221;1772807881991-4&#8243; title=&#8221;Item&#8221;][image_with_animation image_url=&#8221;928&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/item][\/carousel][\/vc_column][vc_column column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h3&#8243; text_color=&#8221;#1c173f&#8221; font_size_min=&#8221;36&#8243; font_size_max=&#8221;45&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; stagger_animation=&#8221;true&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;New Horeca product&#8221; font_size=&#8221;3vw&#8221; font_line_height=&#8221;1.2&#8243; text_direction=&#8221;default&#8221; font_size_tablet=&#8221;4vw&#8221; font_size_phone=&#8221;6vw&#8221;][\/split_line_heading][image_with_animation image_url=&#8221;40&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>The new Flatbread in so many delicious flavors<\/strong><\/p>\n<p>A new filled dough creation \u2014 a little like a cr\u00eape, a little like a pie, yet neither\u2026 and seriously delicious.[\/vc_column_text][nectar_btn size=&#8221;large&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; solid_text_color_override=&#8221;#eff1f0&#8243; icon_family=&#8221;none&#8221; el_class=&#8221;mamas-button&#8221; text=&#8221;\u03a0\u03c1\u03bf\u03ca\u03cc\u03bd\u03c4\u03b1 Horeca&#8221; margin_top=&#8221;20&#8243; margin_bottom=&#8221;20&#8243; url=&#8221;\/about&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#1c173f&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;3%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;3%&#8221; top_padding_tablet=&#8221;6%&#8221; constrain_group_3=&#8221;yes&#8221; bottom_padding_tablet=&#8221;6%&#8221; text_color=&#8221;custom&#8221; custom_text_color=&#8221;#eff1f0&#8243; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h3&#8243; font_size_min=&#8221;36&#8243; font_size_max=&#8221;45&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; stagger_animation=&#8221;true&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Preparation in three simple steps&#8221; font_size=&#8221;3vw&#8221; font_line_height=&#8221;1.2&#8243; text_direction=&#8221;default&#8221; font_size_tablet=&#8221;4vw&#8221; font_size_phone=&#8221;5vw&#8221;][\/split_line_heading][image_with_animation image_url=&#8221;59&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;left-right&#8221; bottom_margin_tablet=&#8221;40px&#8221; bottom_margin_phone=&#8221;40px&#8221; column_element_direction_desktop=&#8221;horizontal&#8221; column_element_direction_tablet=&#8221;horizontal&#8221; column_element_direction_phone=&#8221;horizontal&#8221; column_element_alignment=&#8221;center&#8221; column_element_spacing=&#8221;20px&#8221; desktop_text_alignment=&#8221;left&#8221; tablet_text_alignment=&#8221;left&#8221; phone_text_alignment=&#8221;left&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_right_desktop=&#8221;1px&#8221; border_right_tablet=&#8221;0&#8243; border_right_phone=&#8221;0&#8243; column_border_color=&#8221;#ffffff&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;370&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; el_class=&#8221;svg-130&#8243;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_line_height=&#8221;1.1&#8243; text_direction=&#8221;default&#8221; font_size_desktop=&#8221;18px&#8221; max_width=&#8221;310&#8243;]<strong>Let it thaw in the refrigerator or at room temperature<\/strong>[\/nectar_responsive_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;left-right&#8221; bottom_margin_tablet=&#8221;40px&#8221; bottom_margin_phone=&#8221;40px&#8221; column_element_direction_desktop=&#8221;horizontal&#8221; column_element_direction_tablet=&#8221;horizontal&#8221; column_element_direction_phone=&#8221;horizontal&#8221; column_element_alignment=&#8221;center&#8221; column_element_spacing=&#8221;20px&#8221; desktop_text_alignment=&#8221;left&#8221; tablet_text_alignment=&#8221;left&#8221; phone_text_alignment=&#8221;left&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_right_desktop=&#8221;1px&#8221; border_right_tablet=&#8221;0&#8243; border_right_phone=&#8221;0&#8243; column_border_color=&#8221;#ffffff&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;371&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; el_class=&#8221;svg-130&#8243;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_line_height=&#8221;1.1&#8243; text_direction=&#8221;default&#8221; font_size_desktop=&#8221;18px&#8221; max_width=&#8221;310&#8243;]<strong>If you prefer it hot, preheat the oven to 180\u00b0C and heat it for 5\u2032<\/strong>[\/nectar_responsive_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;left-right&#8221; column_element_direction_desktop=&#8221;horizontal&#8221; column_element_direction_tablet=&#8221;horizontal&#8221; column_element_direction_phone=&#8221;horizontal&#8221; column_element_alignment=&#8221;center&#8221; column_element_spacing=&#8221;20px&#8221; desktop_text_alignment=&#8221;left&#8221; tablet_text_alignment=&#8221;left&#8221; phone_text_alignment=&#8221;left&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;372&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; el_class=&#8221;svg-130&#8243;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_line_height=&#8221;1.1&#8243; text_direction=&#8221;default&#8221; font_size_desktop=&#8221;18px&#8221; max_width=&#8221;310&#8243;]<strong>SERVE<\/strong><br \/>\n<strong>*BEST ENJOYED BY HAND<\/strong>[\/nectar_responsive_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;3%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;3%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;pites&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;60&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;padding-4-percent&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h3&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; stagger_animation=&#8221;true&#8221; content_alignment=&#8221;center&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;For those who want easy, traditional, and high-quality food, Greek Mama\u2019s Pie products are the perfect solution. Enjoy homemade-style pies made by a mom in just a few minutes.&#8221; font_size=&#8221;26px&#8221; max_width=&#8221;750&#8243; text_direction=&#8221;default&#8221; font_line_height=&#8221;1.2&#8243; font_size_tablet=&#8221;26px&#8221; font_size_phone=&#8221;22px&#8221;][\/split_line_heading][image_with_animation image_url=&#8221;40&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;281&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; position_desktop=&#8221;absolute&#8221; top_position_desktop=&#8221;-80px&#8221; left_position_desktop=&#8221;2px&#8221; zindex=&#8221;10&#8243;][image_with_animation image_url=&#8221;285&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; position_desktop=&#8221;absolute&#8221; top_position_desktop=&#8221;-70px&#8221; right_position_desktop=&#8221;2px&#8221; zindex=&#8221;10&#8243;][image_with_animation image_url=&#8221;286&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; position_desktop=&#8221;absolute&#8221; bottom_position_desktop=&#8221;65px&#8221; left_position_desktop=&#8221;-480px&#8221; zindex=&#8221;10&#8243;][image_with_animation image_url=&#8221;288&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; position_desktop=&#8221;absolute&#8221; bottom_position_desktop=&#8221;65px&#8221; right_position_desktop=&#8221;2px&#8221; zindex=&#8221;10&#8243;][nectar_post_grid post_type=&#8221;portfolio&#8221; portfolio_category=&#8221;all&#8221; portfolio_starting_category=&#8221;all&#8221; order=&#8221;DESC&#8221; orderby=&#8221;comment_count&#8221; exclude_current_post=&#8221;yes&#8221; flickity_controls=&#8221;next_prev_arrows_overlaid&#8221; flickity_overflow=&#8221;hidden&#8221; flickity_wrap_around=&#8221;no-wrap&#8221; columns=&#8221;4&#8243; columns_tablet=&#8221;default&#8221; columns_phone=&#8221;default&#8221; desktop_small_cols_flickity=&#8221;4&#8243; tablet_cols_flickity=&#8221;3&#8243; phone_cols_flickity=&#8221;2&#8243; grid_item_spacing=&#8221;none&#8221; grid_item_height=&#8221;40vh&#8221; 4_col_masonry_layout=&#8221;default&#8221; image_size=&#8221;large&#8221; overlaid_aspect_ratio_image_size=&#8221;yes&#8221; overlaid_custom_image_aspect_ratio=&#8221;1-1&#8243; image_loading=&#8221;default&#8221; animation=&#8221;none&#8221; animation_stagger=&#8221;90&#8243; animation_easing=&#8221;default&#8221; heading_tag=&#8221;default&#8221; category_position=&#8221;default&#8221; additional_meta_size=&#8221;default&#8221; custom_fields_location=&#8221;before_post_meta&#8221; grid_style=&#8221;content_overlaid&#8221; text_content_layout=&#8221;all_bottom_left&#8221; color_overlay=&#8221;#eff1f0&#8243; color_overlay_opacity=&#8221;0&#8243; color_overlay_hover_opacity=&#8221;0.4&#8243; text_color=&#8221;dark&#8221; text_color_hover=&#8221;dark&#8221; text_opacity=&#8221;0.0&#8243; text_hover_opacity=&#8221;1&#8243; hover_effect=&#8221;zoom&#8221; border_radius=&#8221;none&#8221; posts_per_page=&#8221;12&#8243; display_type=&#8221;carousel&#8221;][nectar_btn size=&#8221;large&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; solid_text_color_override=&#8221;#eff1f0&#8243; icon_family=&#8221;none&#8221; el_class=&#8221;mamas-button&#8221; text=&#8221;Learn our products&#8221; margin_top=&#8221;20&#8243; margin_bottom=&#8221;20&#8243; url=&#8221;https:\/\/mamaspie.gr\/en\/handmade-pies\/&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#1c173f&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; bottom_padding=&#8221;4%&#8221; text_color=&#8221;custom&#8221; custom_text_color=&#8221;#eff1f0&#8243; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h3&#8243; text_color=&#8221;#eff1f0&#8243; font_size_min=&#8221;36&#8243; font_size_max=&#8221;45&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; stagger_animation=&#8221;true&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;HoReCa professionals&#8221; font_size=&#8221;3vw&#8221; font_line_height=&#8221;1&#8243; text_direction=&#8221;default&#8221; font_size_tablet=&#8221;4vw&#8221; font_size_phone=&#8221;6vw&#8221;][\/split_line_heading][image_with_animation image_url=&#8221;59&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Baked and frozen dough products are ideal for professionals dedicated to providing fresh and delicious products without the hassle of complex preparation. Our products do not require special equipment and can be heated in any oven or even air fryer, avoiding a time-consuming preparation process.[\/vc_column_text][nectar_btn size=&#8221;large&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-1&#8243; solid_text_color_override=&#8221;#1c173f&#8221; icon_family=&#8221;none&#8221; el_class=&#8221;mamas-button&#8221; text=&#8221;Read more&#8221; margin_top=&#8221;20&#8243; margin_bottom=&#8221;20&#8243; url=&#8221;\/en\/horeca&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;564&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;5px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;6%&#8221; text_align=&#8221;center&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;92&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;right&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;custom&#8221; max_width_custom=&#8221;50px&#8221; max_width_custom_tablet=&#8221;50px&#8221; max_width_custom_phone=&#8221;50px&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_btn size=&#8221;jumbo&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-1&#8243; color_override=&#8221;#389c52&#8243; solid_text_color_override=&#8221;#1c173f&#8221; icon_family=&#8221;none&#8221; el_class=&#8221;mamas-button&#8221; text=&#8221;Contact us to collaborate&#8221; margin_top=&#8221;20&#8243; margin_bottom=&#8221;20&#8243; url=&#8221;\/en\/contact&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;91&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;custom&#8221; max_width_custom=&#8221;30px&#8221; max_width_custom_tablet=&#8221;30px&#8221; max_width_custom_phone=&#8221;30px&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;6%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;text-carousel&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h3&#8243; text_color=&#8221;#1c173f&#8221; font_size_min=&#8221;36&#8243; font_size_max=&#8221;45&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; stagger_animation=&#8221;true&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;What do you know about Greek pies?&#8221; font_size=&#8221;3vw&#8221; font_line_height=&#8221;1.2&#8243; text_direction=&#8221;default&#8221; font_size_tablet=&#8221;4vw&#8221; font_size_phone=&#8221;5vw&#8221;][\/split_line_heading][image_with_animation image_url=&#8221;40&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][carousel script=&#8221;flickity&#8221; flickity_formatting=&#8221;default&#8221; desktop_cols_flickity=&#8221;1&#8243; desktop_small_cols_flickity=&#8221;1&#8243; tablet_cols_flickity=&#8221;1&#8243; phone_cols_flickity=&#8221;1&#8243; flickity_controls=&#8221;next_prev_arrows_overlaid&#8221; color=&#8221;accent-color&#8221; flickity_overflow=&#8221;hidden&#8221; flickity_wrap_around=&#8221;wrap&#8221; flickity_spacing=&#8221;30px&#8221; flickity_centered_cells=&#8221;true&#8221; flickity_column_vertical_alignment=&#8221;middle&#8221; column_padding=&#8221;10px&#8221; flickity_element_spacing=&#8221;0&#8243; border_radius=&#8221;none&#8221; autorotate=&#8221;true&#8221; autorotate_type=&#8221;default&#8221; autorotation_speed=&#8221;3000&#8243;][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1772807884041-9&#8243; tab_id=&#8221;1772807884041-10&#8243; title=&#8221;Item&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]There are literally hundreds of different types of pies. Some are salty, some are sweet. Every greek region has some form of pie made from local cheese combined, possibly, with local greens. But all the greek pies have something in common: the \u2018fillo\u2019, a special dough composed by very thin pastry sheets.[\/vc_column_text][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1772807884071-2&#8243; tab_id=&#8221;1772807884072-1&#8243; title=&#8221;Item&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]The pie is a specific type of greek traditional food that holds a special place in local gastronomic culture, as it is among the oldest, simplest and yet most delicious dishes one can find in this mediterranean cuisine.[\/vc_column_text][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1772807884102-1&#8243; tab_id=&#8221;1772807884102-7&#8243; title=&#8221;Item&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]It is a dish that helped feed large families when food was scarce and indeed many greek pies call for just a few very basic ingredients that families almost always had on hand: a little flour and olive oil, cheese, some greens one could forage for on a moment&#8217;s notice. It is the art of creating something fantastic from nearly nothing![\/vc_column_text][\/item][\/carousel][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;267&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;375&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; full_height=&#8221;yes&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;top_to_bottom&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":525,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-756","page","type-page","status-publish","has-post-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mama&#039;s Pie - Mama&#039;s Pie<\/title>\n<meta name=\"description\" content=\"For those who want easy, traditional, and high-quality food, Greek Mama\u2019s Pie products are the perfect solution. Enjoy homemade-style pies made by a mom in just a few minutes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mamaspie.gr\/en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mama&#039;s Pie - Mama&#039;s Pie\" \/>\n<meta property=\"og:description\" content=\"For those who want easy, traditional, and high-quality food, Greek Mama\u2019s Pie products are the perfect solution. Enjoy homemade-style pies made by a mom in just a few minutes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mamaspie.gr\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"Mama&#039;s Pie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Mamas-Pie-111881830195766\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-06T14:45:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mamaspie.gr\/wp-content\/uploads\/2025\/01\/foto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mamaspie.gr\\\/en\\\/\",\"url\":\"https:\\\/\\\/mamaspie.gr\\\/en\\\/\",\"name\":\"Mama's Pie - Mama&#039;s Pie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mamaspie.gr\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mamaspie.gr\\\/en\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mamaspie.gr\\\/en\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mamaspie.gr\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/foto.jpg\",\"datePublished\":\"2024-11-26T10:57:23+00:00\",\"dateModified\":\"2026-03-06T14:45:43+00:00\",\"description\":\"For those who want easy, traditional, and high-quality food, Greek Mama\u2019s Pie products are the perfect solution. Enjoy homemade-style pies made by a mom in just a few minutes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mamaspie.gr\\\/en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mamaspie.gr\\\/en\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mamaspie.gr\\\/en\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mamaspie.gr\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/foto.jpg\",\"contentUrl\":\"https:\\\/\\\/mamaspie.gr\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/foto.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mamaspie.gr\\\/en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0391\u03c1\u03c7\u03b9\u03ba\u03ae\",\"item\":\"https:\\\/\\\/mamaspie.gr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mama&#8217;s Pie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mamaspie.gr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/mamaspie.gr\\\/en\\\/\",\"name\":\"Mama's Pie\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mamaspie.gr\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mamaspie.gr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mamaspie.gr\\\/en\\\/#organization\",\"name\":\"Mama's Pie\",\"url\":\"https:\\\/\\\/mamaspie.gr\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mamaspie.gr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mamaspie.gr\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo-footer-gr.png\",\"contentUrl\":\"https:\\\/\\\/mamaspie.gr\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo-footer-gr.png\",\"width\":2680,\"height\":2308,\"caption\":\"Mama's Pie\"},\"image\":{\"@id\":\"https:\\\/\\\/mamaspie.gr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Mamas-Pie-111881830195766\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mama's Pie - Mama&#039;s Pie","description":"For those who want easy, traditional, and high-quality food, Greek Mama\u2019s Pie products are the perfect solution. Enjoy homemade-style pies made by a mom in just a few minutes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mamaspie.gr\/en\/","og_locale":"en_US","og_type":"article","og_title":"Mama's Pie - Mama&#039;s Pie","og_description":"For those who want easy, traditional, and high-quality food, Greek Mama\u2019s Pie products are the perfect solution. Enjoy homemade-style pies made by a mom in just a few minutes.","og_url":"https:\/\/mamaspie.gr\/en\/","og_site_name":"Mama&#039;s Pie","article_publisher":"https:\/\/www.facebook.com\/Mamas-Pie-111881830195766","article_modified_time":"2026-03-06T14:45:43+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/mamaspie.gr\/wp-content\/uploads\/2025\/01\/foto.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mamaspie.gr\/en\/","url":"https:\/\/mamaspie.gr\/en\/","name":"Mama's Pie - Mama&#039;s Pie","isPartOf":{"@id":"https:\/\/mamaspie.gr\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mamaspie.gr\/en\/#primaryimage"},"image":{"@id":"https:\/\/mamaspie.gr\/en\/#primaryimage"},"thumbnailUrl":"https:\/\/mamaspie.gr\/wp-content\/uploads\/2025\/01\/foto.jpg","datePublished":"2024-11-26T10:57:23+00:00","dateModified":"2026-03-06T14:45:43+00:00","description":"For those who want easy, traditional, and high-quality food, Greek Mama\u2019s Pie products are the perfect solution. Enjoy homemade-style pies made by a mom in just a few minutes.","breadcrumb":{"@id":"https:\/\/mamaspie.gr\/en\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mamaspie.gr\/en\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mamaspie.gr\/en\/#primaryimage","url":"https:\/\/mamaspie.gr\/wp-content\/uploads\/2025\/01\/foto.jpg","contentUrl":"https:\/\/mamaspie.gr\/wp-content\/uploads\/2025\/01\/foto.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/mamaspie.gr\/en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0391\u03c1\u03c7\u03b9\u03ba\u03ae","item":"https:\/\/mamaspie.gr\/en\/"},{"@type":"ListItem","position":2,"name":"Mama&#8217;s Pie"}]},{"@type":"WebSite","@id":"https:\/\/mamaspie.gr\/en\/#website","url":"https:\/\/mamaspie.gr\/en\/","name":"Mama's Pie","description":"","publisher":{"@id":"https:\/\/mamaspie.gr\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mamaspie.gr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mamaspie.gr\/en\/#organization","name":"Mama's Pie","url":"https:\/\/mamaspie.gr\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mamaspie.gr\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mamaspie.gr\/wp-content\/uploads\/2025\/02\/logo-footer-gr.png","contentUrl":"https:\/\/mamaspie.gr\/wp-content\/uploads\/2025\/02\/logo-footer-gr.png","width":2680,"height":2308,"caption":"Mama's Pie"},"image":{"@id":"https:\/\/mamaspie.gr\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Mamas-Pie-111881830195766"]}]}},"_links":{"self":[{"href":"https:\/\/mamaspie.gr\/en\/wp-json\/wp\/v2\/pages\/756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mamaspie.gr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mamaspie.gr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mamaspie.gr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mamaspie.gr\/en\/wp-json\/wp\/v2\/comments?post=756"}],"version-history":[{"count":4,"href":"https:\/\/mamaspie.gr\/en\/wp-json\/wp\/v2\/pages\/756\/revisions"}],"predecessor-version":[{"id":930,"href":"https:\/\/mamaspie.gr\/en\/wp-json\/wp\/v2\/pages\/756\/revisions\/930"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mamaspie.gr\/en\/wp-json\/wp\/v2\/media\/525"}],"wp:attachment":[{"href":"https:\/\/mamaspie.gr\/en\/wp-json\/wp\/v2\/media?parent=756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}